{"id":96,"count":1,"description":"","link":"https:\/\/www.meehawl.com\/Blogfiles\/category\/minnesota\/","name":"Minnesota","slug":"minnesota","taxonomy":"category","parent":0,"meta":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.meehawl.com\/Blogfiles\/category\/minnesota\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.meehawl.com\\\/Blogfiles\\\/wp-json\\\/wp\\\/v2\\\/categories\\\/96\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.meehawl.com\\\/Blogfiles#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.meehawl.com\\\/Blogfiles\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.meehawl.com\\\/Blogfiles\\\/category\\\/minnesota\\\/#listItem\",\"name\":\"Minnesota\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.meehawl.com\\\/Blogfiles\\\/category\\\/minnesota\\\/#listItem\",\"position\":2,\"name\":\"Minnesota\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.meehawl.com\\\/Blogfiles#listItem\",\"name\":\"Home\"}}]},{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.meehawl.com\\\/Blogfiles\\\/wp-json\\\/wp\\\/v2\\\/categories\\\/96\\\/#collectionpage\",\"url\":\"https:\\\/\\\/www.meehawl.com\\\/Blogfiles\\\/wp-json\\\/wp\\\/v2\\\/categories\\\/96\\\/\",\"name\":\"Minnesota | meehawl\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.meehawl.com\\\/Blogfiles\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.meehawl.com\\\/Blogfiles\\\/wp-json\\\/wp\\\/v2\\\/categories\\\/96\\\/#breadcrumblist\"}},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.meehawl.com\\\/Blogfiles\\\/#organization\",\"name\":\"meehawl\",\"description\":\"all that is solid melts into air, all that is holy is profaned\",\"url\":\"https:\\\/\\\/www.meehawl.com\\\/Blogfiles\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"http:\\\/\\\/www.meehawl.com\\\/Blogfiles\\\/wp-content\\\/uploads\\\/2016\\\/02\\\/Mike__Invert-Icon.png\",\"@id\":\"https:\\\/\\\/www.meehawl.com\\\/Blogfiles\\\/wp-json\\\/wp\\\/v2\\\/categories\\\/96\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.meehawl.com\\\/Blogfiles\\\/wp-json\\\/wp\\\/v2\\\/categories\\\/96\\\/#organizationLogo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.meehawl.com\\\/Blogfiles\\\/#website\",\"url\":\"https:\\\/\\\/www.meehawl.com\\\/Blogfiles\\\/\",\"name\":\"meehawl\",\"description\":\"all that is solid melts into air, all that is holy is profaned\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.meehawl.com\\\/Blogfiles\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Minnesota | meehawl","description":"","canonical_url":"https:\/\/www.meehawl.com\/Blogfiles\/category\/minnesota\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/www.meehawl.com\/Blogfiles\/wp-json\/wp\/v2\/categories\/96\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.meehawl.com\/Blogfiles#listItem","position":1,"name":"Home","item":"https:\/\/www.meehawl.com\/Blogfiles","nextItem":{"@type":"ListItem","@id":"https:\/\/www.meehawl.com\/Blogfiles\/category\/minnesota\/#listItem","name":"Minnesota"}},{"@type":"ListItem","@id":"https:\/\/www.meehawl.com\/Blogfiles\/category\/minnesota\/#listItem","position":2,"name":"Minnesota","previousItem":{"@type":"ListItem","@id":"https:\/\/www.meehawl.com\/Blogfiles#listItem","name":"Home"}}]},{"@type":"CollectionPage","@id":"https:\/\/www.meehawl.com\/Blogfiles\/wp-json\/wp\/v2\/categories\/96\/#collectionpage","url":"https:\/\/www.meehawl.com\/Blogfiles\/wp-json\/wp\/v2\/categories\/96\/","name":"Minnesota | meehawl","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/www.meehawl.com\/Blogfiles\/#website"},"breadcrumb":{"@id":"https:\/\/www.meehawl.com\/Blogfiles\/wp-json\/wp\/v2\/categories\/96\/#breadcrumblist"}},{"@type":"Organization","@id":"https:\/\/www.meehawl.com\/Blogfiles\/#organization","name":"meehawl","description":"all that is solid melts into air, all that is holy is profaned","url":"https:\/\/www.meehawl.com\/Blogfiles\/","logo":{"@type":"ImageObject","url":"http:\/\/www.meehawl.com\/Blogfiles\/wp-content\/uploads\/2016\/02\/Mike__Invert-Icon.png","@id":"https:\/\/www.meehawl.com\/Blogfiles\/wp-json\/wp\/v2\/categories\/96\/#organizationLogo"},"image":{"@id":"https:\/\/www.meehawl.com\/Blogfiles\/wp-json\/wp\/v2\/categories\/96\/#organizationLogo"}},{"@type":"WebSite","@id":"https:\/\/www.meehawl.com\/Blogfiles\/#website","url":"https:\/\/www.meehawl.com\/Blogfiles\/","name":"meehawl","description":"all that is solid melts into air, all that is holy is profaned","inLanguage":"en-US","publisher":{"@id":"https:\/\/www.meehawl.com\/Blogfiles\/#organization"}}]}},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.meehawl.com\/Blogfiles\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tMinnesota\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.meehawl.com\/Blogfiles"},{"label":"Minnesota","link":"https:\/\/www.meehawl.com\/Blogfiles\/category\/minnesota\/"}],"_links":{"self":[{"href":"https:\/\/www.meehawl.com\/Blogfiles\/wp-json\/wp\/v2\/categories\/96","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.meehawl.com\/Blogfiles\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.meehawl.com\/Blogfiles\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/www.meehawl.com\/Blogfiles\/wp-json\/wp\/v2\/posts?categories=96"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}